{"id":232,"count":7,"description":"","link":"http:\/\/oeng2665.odns.fr\/beautysuccess\/categorie-produit\/soin-visage-et-corps\/divers-yeux-soin-visage-et-corps\/","name":"Divers yeux","slug":"divers-yeux-soin-visage-et-corps","taxonomy":"product_cat","parent":21,"meta":[],"acf":[],"_links":{"self":[{"href":"http:\/\/oeng2665.odns.fr\/beautysuccess\/wp-json\/wp\/v2\/product_cat\/232"}],"collection":[{"href":"http:\/\/oeng2665.odns.fr\/beautysuccess\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"http:\/\/oeng2665.odns.fr\/beautysuccess\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"http:\/\/oeng2665.odns.fr\/beautysuccess\/wp-json\/wp\/v2\/product_cat\/21"}],"wp:post_type":[{"href":"http:\/\/oeng2665.odns.fr\/beautysuccess\/wp-json\/wp\/v2\/product?product_cat=232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}