{"id":2569,"date":"2020-12-17T17:53:01","date_gmt":"2020-12-17T16:53:01","guid":{"rendered":"http:\/\/oeng2665.odns.fr\/beautysuccess\/produit\/diorshow-liquid-060\/"},"modified":"2020-12-17T17:53:01","modified_gmt":"2020-12-17T16:53:01","slug":"diorshow-liquid-060","status":"publish","type":"product","link":"http:\/\/oeng2665.odns.fr\/beautysuccess\/produit\/diorshow-liquid-060\/","title":{"rendered":"DIORSHOW LIQUID 060"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"comment_status":"closed","ping_status":"open","template":"","meta":[],"product_cat":[20],"product_tag":[],"acf":[],"brands":[{"id":65,"name":"Dior","slug":"dior"}],"_links":{"self":[{"href":"http:\/\/oeng2665.odns.fr\/beautysuccess\/wp-json\/wp\/v2\/product\/2569"}],"collection":[{"href":"http:\/\/oeng2665.odns.fr\/beautysuccess\/wp-json\/wp\/v2\/product"}],"about":[{"href":"http:\/\/oeng2665.odns.fr\/beautysuccess\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"http:\/\/oeng2665.odns.fr\/beautysuccess\/wp-json\/wp\/v2\/comments?post=2569"}],"wp:attachment":[{"href":"http:\/\/oeng2665.odns.fr\/beautysuccess\/wp-json\/wp\/v2\/media?parent=2569"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"http:\/\/oeng2665.odns.fr\/beautysuccess\/wp-json\/wp\/v2\/product_cat?post=2569"},{"taxonomy":"product_tag","embeddable":true,"href":"http:\/\/oeng2665.odns.fr\/beautysuccess\/wp-json\/wp\/v2\/product_tag?post=2569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}